{"id":3037,"date":"2026-07-13T17:12:05","date_gmt":"2026-07-13T20:12:05","guid":{"rendered":"https:\/\/www.blog2.com.ar\/?p=3037"},"modified":"2026-07-13T17:12:07","modified_gmt":"2026-07-13T20:12:07","slug":"yo-no-soy-mi-gemelo","status":"publish","type":"post","link":"https:\/\/www.blog2.com.ar\/index.php\/2026\/07\/13\/yo-no-soy-mi-gemelo\/","title":{"rendered":"Yo no soy mi gemelo"},"content":{"rendered":"\n<p>Un jueves por la tarde voy al supermercado. El ticket no es muy distinto del de la semana anterior. Es un buen d\u00eda para anticipar alguna compra para el fin de semana. El uso de alguna app que brinde el servicio de transporte resulta \u00fatil los d\u00edas no laborables, compra del super bajo el brazo, para compartir una reuni\u00f3n. Momento perfecto para compartir memes y opiniones que se contrastan permanentemente con b\u00fasquedas en chatGPT y el buscador de Google. Por supuesto es m\u00e1s divertido si hablamos con el chat para que responda como si fuera un llamado cualquiera. El mismo chat que sabe qui\u00e9n le est\u00e1 hablando y que nos indic\u00f3 los mejores hoteles seg\u00fan una valoraci\u00f3n de precio\/calidad\/disponibilidad en Amsterdam; o cerca del verano en el sur del mundo.<\/p>\n\n\n\n<p>Cada hotel recibi\u00f3 una transferencia, de alguna cripto, o de alguna tarjeta m\u00e1s tradicional, a\u00fan en su versi\u00f3n virtual. Miles de datos en muy poco tiempo. Miles de datos recogidos por las antenas celulares de una simple caminata por la ciudad. Un DNI asociado a una app de gobierno cruzada con seguros, veh\u00edculos, hijos, obra social y calendario de vacunaci\u00f3n. Y, desde ya, con las declaraciones impositivas. Con un perfil financiero. Con aportes jubilatorios. Con las veces que fuimos al cine este mes. Con el consumo en un kiosko, o en una concesionaria de autos.<\/p>\n\n\n\n<p>La carga de una tarjeta para viajar en la ciudad debita los valores nominales de las tarifas; salvo que se registre, se asocie a un DNI, o a un medio de pago; y entonces habr\u00e1n comprado otros datos m\u00e1s a cambio de un descuento al que no podremos negarnos. Se suman las b\u00fasquedas, Spotify, Netflix, y las c\u00e1maras de video en las calles y estaciones de tren con capacidad de reconocimiento facial; como en las c\u00e1maras de muchos edificios y barrios.<\/p>\n\n\n\n<p><strong>Entrar y salir de cualquier lugar ya es un tr\u00e1mite polic\u00edaco<\/strong>; mientras grandes eventos implementan mecanismos que no permiten salir y volver a ingresar gracias a sus datos, y a una pol\u00edtica de seguridad bastante poco amable. Hay datos sobre si nos movemos, si corremos, si andamos en bici. Hay datos de casi cualquier movimiento que hagamos.<\/p>\n\n\n\n<p>Hay datos que dejamos. En tiempo pasado. Datos que se construyeron mientras accionamos. Datos que pueden oficiar de \u201cprontuario\u201d cuando menos lo esperamos. Cuesti\u00f3n ampliamente discutible.<\/p>\n\n\n\n<p>Ahora vamos m\u00e1s all\u00e1: <strong>sobre los datos del pasado, inferimos datos del futuro<\/strong>. Anticiparemos el comportamiento de las personas. Alguien sabr\u00e1 de antemano qu\u00e9 comprar\u00e9 en el super y qu\u00e9 memes mirar\u00e9 con mis amigos mientras llegan publicidades invasivas sobre hoteles y consumos habituales. \u00bfC\u00f3mo impactar\u00eda en una b\u00fasqueda de empleo mi informaci\u00f3n gen\u00e9tica? \u00bfQui\u00e9n accede a mis historias cl\u00ednicas?<\/p>\n\n\n\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=NPE7i8wuupk\" target=\"_blank\" rel=\"noopener\" title=\"\">Marta Peirano ya advert\u00eda que debemos protegernos de esta forma de espionaje<\/a>, y sus fundamentos son irrefutables: la sola existencia de esta informaci\u00f3n nos hace vulnerables de modos que hoy no podemos prever. En la \u00e9poca de los gemelos digitales seremos observados por lo que podr\u00edamos hacer, en lugar de por lo que hicimos. Un paso m\u00e1s hacia la datificaci\u00f3n de toda nuestra existencia en favor del acceso a informaci\u00f3n valiosa por parte de otros.<\/p>\n\n\n\n<p>Ni siquiera comenzamos la discusi\u00f3n de la soberan\u00eda digital y tecnol\u00f3gica, ni de las posibilidades concretas de la IA. Esto demuestra que los problemas son anteriores a una tecnolog\u00eda en particular. Se trata, en cambio, de conceptos fundamentales, de derechos civiles, y de no aceptar un estado de vigilancia permanente, en favor de la libertad que tan vapuleada est\u00e1 por parte de los mismos promotores de estas tecnolog\u00edas.<\/p>\n\n\n\n<p>Los gemelos comparten ADN, pero se diferencian en sus rasgos epigen\u00e9ticos. \u00bfQu\u00e9 sistema podr\u00eda asemejar su informaci\u00f3n a mi ADN? Ninguno, porque el ADN es una cosa material y la informaci\u00f3n sobre \u00e9l no. <strong>Si validamos la met\u00e1fora del gemelo porque nos resulta \u00fatil; veamos tambi\u00e9n sus l\u00edmites<\/strong>: la informaci\u00f3n sobre alguien no es alguien. En todo caso tendremos una pista inexacta de su comportamiento. <a href=\"https:\/\/www.blog2.com.ar\/index.php\/2023\/03\/27\/de-bichos-virtuales-y-nomenclaturas-articuladoras\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Los errores pueden ser car\u00edsimos<\/a>; <a href=\"https:\/\/www.simonweckert.com\/googlemapshacks.html\" target=\"_blank\" rel=\"noopener\" title=\"\">las burlas pueden ser geniales<\/a>; pero la vulnerabilidad siempre permanece.<\/p>\n\n\n\n<p><strong>Nuestra vulnerabilidad es la posibilidad de existencia de estos sistemas<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gemelo digital: si validamos la met\u00e1fora del gemelo porque nos resulta \u00fatil; veamos tambi\u00e9n sus l\u00edmites.<\/p>\n","protected":false},"author":2,"featured_media":3039,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,4,161],"tags":[1705,1706,359,1704,385],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3037"}],"collection":[{"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3037"}],"version-history":[{"count":2,"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3037\/revisions"}],"predecessor-version":[{"id":3040,"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/3037\/revisions\/3040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/media\/3039"}],"wp:attachment":[{"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blog2.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}